{"id":22936,"date":"2016-04-01T02:32:03","date_gmt":"2016-04-01T02:32:03","guid":{"rendered":"https:\/\/www.bioanalyt.com\/stories\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\/"},"modified":"2016-04-01T02:32:03","modified_gmt":"2016-04-01T02:32:03","slug":"plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc","status":"publish","type":"stories","link":"https:\/\/www.bioanalyt.com\/fr\/stories\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\/","title":{"rendered":"Plus que des racines : Mesurer les nutriments dans l&rsquo;ensemble de la plante de manioc"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><em>Feuilles de manioc congel\u00e9es utilis\u00e9es pour l&rsquo;analyse<\/em><\/p>\n<p>L&rsquo;Institut international d&rsquo;agriculture tropicale (IITA), l&rsquo;Universit\u00e9 de Potsdam et l&rsquo;Universit\u00e9 du Ghana, Legon, avec le soutien de la GIZ, collaborent \u00e0 un projet visant \u00e0 accro\u00eetre l&rsquo;impact de la biofortification du manioc au Cameroun et au Ghana.<\/p>\n<p>Le manioc, un arbuste ligneux dont la racine comestible est r\u00e9colt\u00e9e dans les zones tropicales et subtropicales, est un aliment de base important dans toute l&rsquo;Afrique. Au Ghana, les racines sont utilis\u00e9es pour un plat populaire appel\u00e9 gari, tandis que les feuilles sont ajout\u00e9es aux soupes et aux sauces. <\/p>\n<p>En partenariat avec l&rsquo;IITA, BioAnalyt a d\u00e9velopp\u00e9 des m\u00e9thodes rapides pour la d\u00e9termination du b\u00eata-carot\u00e8ne dans le manioc frais. Ce projet vise \u00e0 d\u00e9velopper des protocoles pour d\u00e9terminer non seulement le b\u00eata-carot\u00e8ne dans les racines fra\u00eeches de manioc, mais aussi dans le manioc transform\u00e9, ainsi que le zinc et le fer dans les feuilles de manioc. Dans le cadre de ce projet, BioAnalyt contribue \u00e0 la formation et \u00e0 l&rsquo;\u00e9quipement pour l&rsquo;analyse des micronutriments, ainsi qu&rsquo;au conseil technique, au d\u00e9veloppement de protocoles et de mat\u00e9riaux de r\u00e9f\u00e9rence. Les m\u00e9thodes d\u00e9velopp\u00e9es profiteront aux chercheurs travaillant sur la bio-fortification du manioc &#8211; les outils permettront une d\u00e9tection plus rapide du b\u00eata-carot\u00e8ne et donc la s\u00e9lection de races riches en provitamine A. Le b\u00eata-carot\u00e8ne est un compos\u00e9 sensible qui est partiellement d\u00e9grad\u00e9 au cours de la transformation de la racine de manioc pour la fabrication du gari ou d&rsquo;autres produits. L&rsquo;analyse du produit final permettra d&rsquo;\u00e9valuer la quantit\u00e9 de micronutriments qui parvient au consommateur.     <\/p>\n<p>Les feuilles de manioc sont \u00e9galement une riche source de b\u00eata-carot\u00e8ne et de min\u00e9raux tels que le fer et le zinc. La m\u00e9thodologie traditionnelle pour mesurer les min\u00e9raux dans les feuilles n\u00e9cessite beaucoup de travail et d&rsquo;argent, ainsi qu&rsquo;un \u00e9quipement de laboratoire sp\u00e9cialis\u00e9. Le d\u00e9veloppement d&rsquo;une m\u00e9thode facile \u00e0 appliquer sur le terrain facilitera la recherche et la s\u00e9lection de vari\u00e9t\u00e9s plus nutritives. Les petits exploitants locaux, les organisations agricoles et les ONG b\u00e9n\u00e9ficieront tous de l&rsquo;acc\u00e8s \u00e0 des races de manioc am\u00e9lior\u00e9es, \u00e0 haut rendement et riches en provitamine A.   <\/p>\n<figure id=\"attachment_16785\" aria-describedby=\"caption-attachment-16785\" style=\"width: 749px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-16785 size-full\" src=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2016\/04\/Iron-Recovery.webp\" alt=\"Anthony Acquatey-Mensah et Dr. Anna Zhenchuk \u00e9tudient la r\u00e9cup\u00e9ration du Fe en utilisant diff\u00e9rentes m\u00e9thodes de traitement des \u00e9chantillons.\" width=\"749\" height=\"324\" srcset=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2016\/04\/Iron-Recovery.webp 749w, https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2016\/04\/Iron-Recovery-300x130.webp 300w, https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2016\/04\/Iron-Recovery-600x260.webp 600w\" sizes=\"(max-width: 749px) 100vw, 749px\" \/><figcaption id=\"caption-attachment-16785\" class=\"wp-caption-text\">Anthony Acquatey-Mensah et Dr. Anna Zhenchuk \u00e9tudient la r\u00e9cup\u00e9ration du Fe en utilisant diff\u00e9rentes m\u00e9thodes de traitement des \u00e9chantillons.<\/figcaption><\/figure>\n<p>La port\u00e9e du projet va au-del\u00e0 de l&rsquo;\u00e9laboration de m\u00e9thodes et vise \u00e9galement \u00e0 am\u00e9liorer les capacit\u00e9s locales et \u00e0 encourager les \u00e9changes internationaux. Pour le coup d&rsquo;envoi en mai 2015, un atelier a \u00e9t\u00e9 organis\u00e9 \u00e0 l&rsquo;Universit\u00e9 du Ghana, Legon, pour former aux m\u00e9thodes analytiques actuelles. Deux \u00e9tudiants de l&rsquo;Universit\u00e9 du Ghana, Legon et de l&rsquo;Universit\u00e9 de Potsdam, Allemagne, participeront \u00e0 un \u00e9change acad\u00e9mique.  <\/p>\n<p>Anthony Acquatey-Mensah, \u00e9tudiant en master de sciences alimentaires \u00e0 l&rsquo;universit\u00e9 du Ghana \u00e0 Legon, a pass\u00e9 deux mois avec l&rsquo;universit\u00e9 de Potsdam et BioAnalyt en Allemagne. Il a consacr\u00e9 son temps \u00e0 d&rsquo;intenses travaux exp\u00e9rimentaux sur les racines, les feuilles et les produits du manioc. Il a effectu\u00e9 des tests pour le fer et le zinc en utilisant l&rsquo;ICP-MS avec diff\u00e9rentes techniques d&rsquo;incin\u00e9ration et les kits de test iCheck Iron et iCheck Zinc. Pour le b\u00eata-carot\u00e8ne, la m\u00e9thode de r\u00e9f\u00e9rence HPLC a \u00e9t\u00e9 utilis\u00e9e avec diff\u00e9rentes techniques de pr\u00e9paration des \u00e9chantillons et compar\u00e9e \u00e0 iCheck Carotene.   <\/p>\n<p>Le projet devrait s&rsquo;achever cette ann\u00e9e, avec un deuxi\u00e8me atelier au Cameroun pour diffuser les r\u00e9sultats et former de nouveaux protocoles. Restez \u00e0 l&rsquo;\u00e9coute pour conna\u00eetre l&rsquo;\u00e9tat d&rsquo;avancement du projet et obtenir une interview d&rsquo;Anthony sur sa passion pour la recherche, le temps pass\u00e9 en laboratoire et, croyez-le ou non, la po\u00e9sie. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>En collaboration avec l&rsquo;Institut international d&rsquo;agriculture tropicale, nous d\u00e9veloppons des m\u00e9thodes de mesure du fer et du zinc dans les feuilles et les racines de manioc.<\/p>\n","protected":false},"author":10,"featured_media":20119,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1228,1013,990],"tags":[1230,1229,1231,1015],"class_list":["post-22936","stories","type-stories","status-publish","has-post-thumbnail","hentry","category-biofortification-fr","category-blog-fr","category-fortification-des-aliments","tag-essais-sur-le-terrain","tag-lelevage","tag-pro-vitamine-a-manioc","tag-tests-alimentaires"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plus que des racines : Mesurer les nutriments dans l&#039;ensemble de la plante de manioc - Bioanalyt<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez comment BioAnalyt et ses partenaires font progresser les m\u00e9thodes d&#039;analyse rapide du b\u00eata-carot\u00e8ne, du fer et du zinc dans les racines et les feuilles de manioc afin de soutenir les efforts de biofortification au Ghana et au Cameroun.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bioanalyt.com\/fr\/stories\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plus que des racines : Mesurer les nutriments dans l&#039;ensemble de la plante de manioc - Bioanalyt\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez comment BioAnalyt et ses partenaires font progresser les m\u00e9thodes d&#039;analyse rapide du b\u00eata-carot\u00e8ne, du fer et du zinc dans les racines et les feuilles de manioc afin de soutenir les efforts de biofortification au Ghana et au Cameroun.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bioanalyt.com\/fr\/stories\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\/\" \/>\n<meta property=\"og:site_name\" content=\"Bioanalyt\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2016\/04\/Cassava-Plant-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"749\" \/>\n\t<meta property=\"og:image:height\" content=\"324\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\\\/\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\\\/\",\"name\":\"Plus que des racines : Mesurer les nutriments dans l'ensemble de la plante de manioc - Bioanalyt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/Cassava-Plant-1.webp\",\"datePublished\":\"2016-04-01T02:32:03+00:00\",\"description\":\"D\u00e9couvrez comment BioAnalyt et ses partenaires font progresser les m\u00e9thodes d'analyse rapide du b\u00eata-carot\u00e8ne, du fer et du zinc dans les racines et les feuilles de manioc afin de soutenir les efforts de biofortification au Ghana et au Cameroun.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/Cassava-Plant-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/Cassava-Plant-1.webp\",\"width\":749,\"height\":324,\"caption\":\"Cassava Plan\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plus que des racines : Mesurer les nutriments dans l'ensemble de la plante de manioc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#website\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/\",\"name\":\"Bioanalyt\",\"description\":\"Measure for life\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bioanalyt.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#organization\",\"name\":\"Bioanalyt\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Logo-Horizontal.svg\",\"contentUrl\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Logo-Horizontal.svg\",\"width\":112,\"height\":64,\"caption\":\"Bioanalyt\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bioanalyt\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BioAnalyt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plus que des racines : Mesurer les nutriments dans l'ensemble de la plante de manioc - Bioanalyt","description":"D\u00e9couvrez comment BioAnalyt et ses partenaires font progresser les m\u00e9thodes d'analyse rapide du b\u00eata-carot\u00e8ne, du fer et du zinc dans les racines et les feuilles de manioc afin de soutenir les efforts de biofortification au Ghana et au Cameroun.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bioanalyt.com\/fr\/stories\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\/","og_locale":"fr_FR","og_type":"article","og_title":"Plus que des racines : Mesurer les nutriments dans l'ensemble de la plante de manioc - Bioanalyt","og_description":"D\u00e9couvrez comment BioAnalyt et ses partenaires font progresser les m\u00e9thodes d'analyse rapide du b\u00eata-carot\u00e8ne, du fer et du zinc dans les racines et les feuilles de manioc afin de soutenir les efforts de biofortification au Ghana et au Cameroun.","og_url":"https:\/\/www.bioanalyt.com\/fr\/stories\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\/","og_site_name":"Bioanalyt","og_image":[{"width":749,"height":324,"url":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2016\/04\/Cassava-Plant-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\/","url":"https:\/\/www.bioanalyt.com\/fr\/stories\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\/","name":"Plus que des racines : Mesurer les nutriments dans l'ensemble de la plante de manioc - Bioanalyt","isPartOf":{"@id":"https:\/\/www.bioanalyt.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\/#primaryimage"},"image":{"@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2016\/04\/Cassava-Plant-1.webp","datePublished":"2016-04-01T02:32:03+00:00","description":"D\u00e9couvrez comment BioAnalyt et ses partenaires font progresser les m\u00e9thodes d'analyse rapide du b\u00eata-carot\u00e8ne, du fer et du zinc dans les racines et les feuilles de manioc afin de soutenir les efforts de biofortification au Ghana et au Cameroun.","breadcrumb":{"@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bioanalyt.com\/fr\/stories\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\/#primaryimage","url":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2016\/04\/Cassava-Plant-1.webp","contentUrl":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2016\/04\/Cassava-Plant-1.webp","width":749,"height":324,"caption":"Cassava Plan"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/plus-que-des-racines-mesurer-les-nutriments-dans-lensemble-de-la-plante-de-manioc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bioanalyt.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Plus que des racines : Mesurer les nutriments dans l'ensemble de la plante de manioc"}]},{"@type":"WebSite","@id":"https:\/\/www.bioanalyt.com\/#website","url":"https:\/\/www.bioanalyt.com\/","name":"Bioanalyt","description":"Measure for life","publisher":{"@id":"https:\/\/www.bioanalyt.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bioanalyt.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.bioanalyt.com\/#organization","name":"Bioanalyt","url":"https:\/\/www.bioanalyt.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bioanalyt.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/09\/Logo-Horizontal.svg","contentUrl":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/09\/Logo-Horizontal.svg","width":112,"height":64,"caption":"Bioanalyt"},"image":{"@id":"https:\/\/www.bioanalyt.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/bioanalyt\/","https:\/\/www.youtube.com\/user\/BioAnalyt"]}]}},"_links":{"self":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/stories\/22936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/stories"}],"about":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/types\/stories"}],"author":[{"embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"version-history":[{"count":0,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/stories\/22936\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/media\/20119"}],"wp:attachment":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/media?parent=22936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/categories?post=22936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/tags?post=22936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}