{"id":22910,"date":"2019-02-25T17:22:29","date_gmt":"2019-02-25T17:22:29","guid":{"rendered":"https:\/\/www.bioanalyt.com\/stories\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\/"},"modified":"2026-03-30T09:16:22","modified_gmt":"2026-03-30T09:16:22","slug":"sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode","status":"publish","type":"stories","link":"https:\/\/www.bioanalyt.com\/fr\/stories\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\/","title":{"rendered":"Sel doublement enrichi &#8211; iCheck peut mesurer le fer et l&rsquo;iode"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>Plus d&rsquo;un tiers de la population mondiale souffre de carences en iode et en fer, ce qui repr\u00e9sente un grave risque pour la sant\u00e9 publique. Depuis des d\u00e9cennies, le sel est enrichi en iode avec succ\u00e8s dans de nombreux pays du monde. Le sel est une matrice alimentaire id\u00e9ale pour les efforts d&rsquo;enrichissement, car il est bon march\u00e9 et largement consomm\u00e9 dans les r\u00e9gions o\u00f9 les carences en micronutriments sont fr\u00e9quentes.  <\/p>\n<p>Le sel doublement enrichi (SDE) est un sel enrichi \u00e0 la fois en iode et en fer. Il est g\u00e9n\u00e9ralement enrichi en iodure ou en iodate de potassium (pour l&rsquo;iode) et en sulfate ferreux, en fumarate ferreux, en pyrophosphate ferrique ou en EDTA ferrique sodique (pour le fer). Les carences en iode et en fer peuvent \u00eatre \u00e9vit\u00e9es ou r\u00e9duites \u00e0 peu de frais par l&rsquo;apport alimentaire de DFS. Toutefois, les compos\u00e9s ferreux peuvent r\u00e9agir avec l&rsquo;iodate, ce qui peut entra\u00eener une perte d&rsquo;iode et l&rsquo;oxydation du fer ferreux en fer :   <\/p>\n<p style=\"text-align: center;\"><strong>2 I5+ + 10 Fe2+ \u2192 I2 + 10 Fe3+<\/strong><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-16760 size-full\" src=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2019\/02\/Picture-3.webp\" alt=\"Distribution du fumarate ferreux dans le sel\" width=\"873\" height=\"289\" srcset=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2019\/02\/Picture-3.webp 873w, https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2019\/02\/Picture-3-300x99.webp 300w, https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2019\/02\/Picture-3-768x254.webp 768w, https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2019\/02\/Picture-3-600x199.webp 600w\" sizes=\"(max-width: 873px) 100vw, 873px\" \/><br \/>\nL&rsquo;interaction entre le fer et l&rsquo;iode est r\u00e9duite ou \u00e9limin\u00e9e par l&rsquo;encapsulation du fer. Plusieurs \u00e9tudes ont \u00e9t\u00e9 men\u00e9es sur la stabilit\u00e9, l&rsquo;acceptabilit\u00e9 et la biodisponibilit\u00e9 des diff\u00e9rentes formes d&rsquo;iode et de fer utilis\u00e9es dans la formulation du DFS. Ces \u00e9tudes ont r\u00e9v\u00e9l\u00e9 qu&rsquo;une combinaison d&rsquo;iodate de potassium et de fumarate ferreux \u00e9tait plus stable dans les conditions de stockage, pr\u00e9sentait une meilleure biodisponibilit\u00e9 et \u00e9tait plus acceptable pour les consommateurs.  <\/p>\n<p>L&rsquo;un des moyens de d\u00e9terminer le succ\u00e8s des efforts de fortification consiste \u00e0 mesurer les micronutriments dans les aliments et les fluides corporels. Le titrage iodom\u00e9trique est la m\u00e9thode la plus courante pour analyser l&rsquo;iode, tandis que la spectrom\u00e9trie d&rsquo;absorption atomique (SAA) est largement utilis\u00e9e pour l&rsquo;analyse du fer dans les aliments et les \u00e9chantillons biologiques. R\u00e9cemment, la spectrom\u00e9trie de masse \u00e0 plasma inductif (ICP-MS) a \u00e9t\u00e9 utilis\u00e9e pour l&rsquo;analyse de l&rsquo;iode et du fer. <a href=\"https:\/\/www.bioanalyt.com\/product\/icheck-iodine\/\" target=\"_blank\" rel=\"noopener noreferrer\">iCheck Iodine<\/a> et <a href=\"https:\/\/www.bioanalyt.com\/product\/icheck-iron\/\" target=\"_blank\" rel=\"noopener noreferrer\">iCheck Iron<\/a> sont des appareils rapides, peu co\u00fbteux, portables et faciles \u00e0 utiliser, mis au point par BioAnalyt GmbH (Teltow, Allemagne) pour mesurer respectivement l&rsquo;iode et le fer dans les aliments. Les teneurs en iode et en fer de deux \u00e9chantillons diff\u00e9rents de DFS ont \u00e9t\u00e9 mesur\u00e9es \u00e0 l&rsquo;aide des appareils iCheck Iodine et iCheck Iron respectivement.    <\/p>\n<p>La mesure de l&rsquo;iode dans le DFS \u00e0 l&rsquo;aide de l&rsquo;appareil iCheck Iodine a donn\u00e9 un taux de r\u00e9cup\u00e9ration de 93 % \u00b1 5 % par rapport aux mesures de l&rsquo;ICP-MS. La teneur en fer du DFS a \u00e9t\u00e9 mesur\u00e9e \u00e0 l&rsquo;aide du dispositif iCheck Iron. La r\u00e9cup\u00e9ration du fer dans l&rsquo;\u00e9chantillon \u00e9tait de 70 % \u00b1 30 % par rapport aux r\u00e9sultats de l&rsquo;ICP-MS. Les taux de r\u00e9cup\u00e9ration du fer relativement faibles sont dus \u00e0 l&rsquo;h\u00e9t\u00e9rog\u00e9n\u00e9it\u00e9 du fumarate ferreux dans l&rsquo;\u00e9chantillon, ainsi qu&rsquo;\u00e0 sa faible solubilit\u00e9, m\u00eame dans l&rsquo;HCl 0,2M. Cela signifie qu&rsquo;un \u00e9chantillon plus important doit \u00eatre pr\u00e9lev\u00e9 lors des mesures du fer et qu&rsquo;il faut s&rsquo;assurer que la majeure partie du fumarate ferreux est dissoute avant d&rsquo;effectuer les mesures.<br \/>\n\t\t<div data-elementor-type=\"section\" data-elementor-id=\"23959\" class=\"elementor elementor-23959 elementor-23935\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-f9ff693 e-flex e-con-boxed e-con e-parent\" data-id=\"f9ff693\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d8d573f e-con-full e-flex e-con e-child\" data-id=\"d8d573f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37d2a6d elementor-widget elementor-widget-image\" data-id=\"37d2a6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2025\/06\/iron-image.webp\" class=\"attachment-large size-large wp-image-21603\" alt=\"\" srcset=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2025\/06\/iron-image.webp 800w, https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2025\/06\/iron-image-300x200.webp 300w, https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2025\/06\/iron-image-768x512.webp 768w, https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2025\/06\/iron-image-600x400.webp 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-763a193 e-con-full e-flex e-con e-child\" data-id=\"763a193\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-992d986 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"992d986\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><strong>iCheck Iron<\/strong><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7ca672 elementor-widget elementor-widget-heading\" data-id=\"a7ca672\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Mesure le fer dans les aliments.<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d8e90f elementor-widget elementor-widget-button\" data-id=\"2d8e90f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.bioanalyt.com\/fr\/product\/icheck-iron\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Regarder \u00e0 l'int\u00e9rieur<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<br \/>\n\t\t<div data-elementor-type=\"section\" data-elementor-id=\"23957\" class=\"elementor elementor-23957 elementor-23936\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-f9ff693 e-flex e-con-boxed e-con e-parent\" data-id=\"f9ff693\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d8d573f e-con-full e-flex e-con e-child\" data-id=\"d8d573f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37d2a6d elementor-widget elementor-widget-image\" data-id=\"37d2a6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"610\" src=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2025\/06\/lodine-image.webp\" class=\"attachment-large size-large wp-image-21604\" alt=\"\" srcset=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2025\/06\/lodine-image.webp 800w, https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2025\/06\/lodine-image-300x229.webp 300w, https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2025\/06\/lodine-image-768x586.webp 768w, https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2025\/06\/lodine-image-600x458.webp 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-763a193 e-con-full e-flex e-con e-child\" data-id=\"763a193\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-992d986 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"992d986\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><strong>iCheck Iodine<\/strong><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7ca672 elementor-widget elementor-widget-heading\" data-id=\"a7ca672\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Mesure l'iode dans le sel.<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d8e90f elementor-widget elementor-widget-button\" data-id=\"2d8e90f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.bioanalyt.com\/fr\/product\/icheck-iodine\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Regarder \u00e0 l'int\u00e9rieur<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plus d&rsquo;un tiers de la population mondiale souffre de carences en iode et en fer, ce qui repr\u00e9sente un grave risque pour la sant\u00e9 publique.<\/p>\n","protected":false},"author":1,"featured_media":18774,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1013,990,1001,1077,1096],"tags":[1068,1074,1079],"class_list":["post-22910","stories","type-stories","status-publish","has-post-thumbnail","hentry","category-blog-fr","category-fortification-des-aliments","category-general-fr","category-nouvelles-de-lentreprise","category-sel","tag-aliments-enrichis","tag-le-fer","tag-nos-produits"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sel doublement enrichi | Carence en fer et en iode | Bioanalyt<\/title>\n<meta name=\"description\" content=\"Les carences en fer et en iode touchent un tiers de la population mondiale. Le sel doublement enrichi est une source de pr\u00e9vention de cette carence.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bioanalyt.com\/fr\/stories\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sel doublement enrichi | Carence en fer et en iode | Bioanalyt\" \/>\n<meta property=\"og:description\" content=\"Les carences en fer et en iode touchent un tiers de la population mondiale. Le sel doublement enrichi est une source de pr\u00e9vention de cette carence.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bioanalyt.com\/fr\/stories\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\/\" \/>\n<meta property=\"og:site_name\" content=\"Bioanalyt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-30T09:16:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2019\/02\/Double-Fortified.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"534\" \/>\n\t<meta property=\"og:image:height\" content=\"356\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\\\/\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\\\/\",\"name\":\"Sel doublement enrichi | Carence en fer et en iode | Bioanalyt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Double-Fortified.jpg\",\"datePublished\":\"2019-02-25T17:22:29+00:00\",\"dateModified\":\"2026-03-30T09:16:22+00:00\",\"description\":\"Les carences en fer et en iode touchent un tiers de la population mondiale. Le sel doublement enrichi est une source de pr\u00e9vention de cette carence.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Double-Fortified.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Double-Fortified.jpg\",\"width\":534,\"height\":356,\"caption\":\"Salt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sel doublement enrichi &#8211; iCheck peut mesurer le fer et l&#8217;iode\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#website\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/\",\"name\":\"Bioanalyt\",\"description\":\"Measure for life\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bioanalyt.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#organization\",\"name\":\"Bioanalyt\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Logo-Horizontal.svg\",\"contentUrl\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Logo-Horizontal.svg\",\"width\":112,\"height\":64,\"caption\":\"Bioanalyt\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bioanalyt\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BioAnalyt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sel doublement enrichi | Carence en fer et en iode | Bioanalyt","description":"Les carences en fer et en iode touchent un tiers de la population mondiale. Le sel doublement enrichi est une source de pr\u00e9vention de cette carence.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bioanalyt.com\/fr\/stories\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\/","og_locale":"fr_FR","og_type":"article","og_title":"Sel doublement enrichi | Carence en fer et en iode | Bioanalyt","og_description":"Les carences en fer et en iode touchent un tiers de la population mondiale. Le sel doublement enrichi est une source de pr\u00e9vention de cette carence.","og_url":"https:\/\/www.bioanalyt.com\/fr\/stories\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\/","og_site_name":"Bioanalyt","article_modified_time":"2026-03-30T09:16:22+00:00","og_image":[{"width":534,"height":356,"url":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2019\/02\/Double-Fortified.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\/","url":"https:\/\/www.bioanalyt.com\/fr\/stories\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\/","name":"Sel doublement enrichi | Carence en fer et en iode | Bioanalyt","isPartOf":{"@id":"https:\/\/www.bioanalyt.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\/#primaryimage"},"image":{"@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2019\/02\/Double-Fortified.jpg","datePublished":"2019-02-25T17:22:29+00:00","dateModified":"2026-03-30T09:16:22+00:00","description":"Les carences en fer et en iode touchent un tiers de la population mondiale. Le sel doublement enrichi est une source de pr\u00e9vention de cette carence.","breadcrumb":{"@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bioanalyt.com\/fr\/stories\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\/#primaryimage","url":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2019\/02\/Double-Fortified.jpg","contentUrl":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2019\/02\/Double-Fortified.jpg","width":534,"height":356,"caption":"Salt"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/sel-doublement-enrichi-icheck-peut-mesurer-le-fer-et-liode\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bioanalyt.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Sel doublement enrichi &#8211; iCheck peut mesurer le fer et l&#8217;iode"}]},{"@type":"WebSite","@id":"https:\/\/www.bioanalyt.com\/#website","url":"https:\/\/www.bioanalyt.com\/","name":"Bioanalyt","description":"Measure for life","publisher":{"@id":"https:\/\/www.bioanalyt.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bioanalyt.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.bioanalyt.com\/#organization","name":"Bioanalyt","url":"https:\/\/www.bioanalyt.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bioanalyt.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/09\/Logo-Horizontal.svg","contentUrl":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/09\/Logo-Horizontal.svg","width":112,"height":64,"caption":"Bioanalyt"},"image":{"@id":"https:\/\/www.bioanalyt.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/bioanalyt\/","https:\/\/www.youtube.com\/user\/BioAnalyt"]}]}},"_links":{"self":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/stories\/22910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/stories"}],"about":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/types\/stories"}],"author":[{"embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/stories\/22910\/revisions"}],"predecessor-version":[{"id":26384,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/stories\/22910\/revisions\/26384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/media\/18774"}],"wp:attachment":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/media?parent=22910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/categories?post=22910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/tags?post=22910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}