{"id":22874,"date":"2020-03-27T13:31:58","date_gmt":"2020-03-27T13:31:58","guid":{"rendered":"https:\/\/www.bioanalyt.com\/stories\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\/"},"modified":"2020-03-27T13:31:58","modified_gmt":"2020-03-27T13:31:58","slug":"en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium","status":"publish","type":"stories","link":"https:\/\/www.bioanalyt.com\/fr\/stories\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\/","title":{"rendered":"En savoir plus sur les vitamines et les min\u00e9raux : Vitamine D et calcium"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>Inspir\u00e9 par la publication de <a href=\"https:\/\/sightandlife.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Sight and Life<\/a> \u00ab\u00a0<a href=\"https:\/\/sightandlife.org\/wp-content\/uploads\/2017\/03\/SAL_MVLex_web.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Vitamins and Minerals : A Brief Guide<\/a>\u00ab\u00a0, nous poursuivons notre s\u00e9rie \u00a0\u00bb <a href=\"https:\/\/www.bioanalyt.com\/learn-vitamins-minerals\/\" target=\"_blank\" rel=\"noopener noreferrer\">Learn About Your Vitamins and Minerals<\/a> \u00a0\u00bb en discutant de la vitamine D et du calcium.<\/p>\n<p><strong>Vitamine D<\/strong><\/p>\n<p>Souvent surnomm\u00e9e \u00ab\u00a0<em>vitamine du soleil<\/em>\u00ab\u00a0, la vitamine D est une vitamine liposoluble qui peut \u00eatre produite naturellement par le corps humain en r\u00e9ponse \u00e0 l&rsquo;exposition au soleil. La vitamine D, associ\u00e9e au calcium et au phosphore, contribue \u00e0 la bonne croissance des os. La vitamine D joue un r\u00f4le particuli\u00e8rement important en facilitant l&rsquo;absorption du calcium et du phosphore, qui aident les os \u00e0 devenir plus denses et plus solides. La vitamine D a \u00e9galement d&rsquo;autres fonctions dans l&rsquo;organisme, notamment la modulation de la croissance cellulaire, la fonction neuromusculaire et immunitaire et la r\u00e9duction de l&rsquo;inflammation.   <\/p>\n<p><strong>Sources de vitamine D.<\/strong> S&rsquo;exposer suffisamment au soleil est le moyen le plus efficace d&rsquo;aider l&rsquo;organisme \u00e0 produire suffisamment de vitamine D. Toutefois, il peut \u00eatre difficile de s&rsquo;exposer suffisamment au soleil, surtout pendant les mois d&rsquo;hiver les plus froids, dans les r\u00e9gions o\u00f9 le soleil ne brille pas toujours ou o\u00f9 il est courant de porter des v\u00eatements couvrants. Les poissons gras, le b\u0153uf, le veau, les champignons et le jaune d&rsquo;\u0153uf sont des sources alimentaires de vitamine D qui peuvent \u00eatre utiles. Les suppl\u00e9ments de vitamine D ou les aliments enrichis en vitamine D (tels que les produits laitiers, l&rsquo;huile v\u00e9g\u00e9tale et certaines c\u00e9r\u00e9ales) sont \u00e9galement utiles pour pr\u00e9venir les carences.  <\/p>\n<p><strong>Carence en vitamine D et pr\u00e9vention.<\/strong>  La carence en vitamine D a des effets n\u00e9gatifs sur la sant\u00e9 des os, tant chez les enfants que chez les adultes. Le rachitisme, l&rsquo;ost\u00e9omalacie et l&rsquo;ost\u00e9oporose sont des maladies courantes associ\u00e9es \u00e0 la carence en vitamine D. Le rachitisme touche les jeunes enfants, surtout entre 6 et 36 mois, et est associ\u00e9 \u00e0 des os faibles et mous, \u00e0 un retard de croissance et parfois \u00e0 des d\u00e9formations permanentes du squelette. Les enfants qui ne consomment pas d&rsquo;aliments compl\u00e9mentaires ad\u00e9quats apr\u00e8s l&rsquo;\u00e2ge de 6 mois et ceux qui sont peu ou pas expos\u00e9s \u00e0 la lumi\u00e8re du soleil courent un risque plus \u00e9lev\u00e9 de carence en vitamine D. En effet, le lait maternel seul ne suffit pas \u00e0 pr\u00e9venir la carence en vitamine D. En effet, le lait maternel seul est une mauvaise source de vitamine D.    <\/p>\n<p>Plus fr\u00e9quente chez les adultes et les personnes \u00e2g\u00e9es, l&rsquo;ost\u00e9omalacie est l&rsquo;affaiblissement des os pendant la formation ou la consolidation osseuse, et l&rsquo;ost\u00e9oporose est une affection qui se traduit par des os poreux. Bien que le corps absorbe et remplace constamment le tissu osseux, ces conditions signifient que la cr\u00e9ation de nouveaux os ne peut pas suivre l&rsquo;\u00e9limination des vieux os. La carence en vitamine D peut \u00eatre \u00e9vit\u00e9e en passant du temps au soleil chaque jour, en mangeant un large \u00e9ventail d&rsquo;aliments contenant de la vitamine D et\/ou en prenant des suppl\u00e9ments lorsque les deux premi\u00e8res options ne sont pas disponibles ou pratiques.  <\/p>\n<figure id=\"attachment_16593\" aria-describedby=\"caption-attachment-16593\" style=\"width: 603px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-16593 size-full\" src=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2020\/03\/Calcium.webp\" alt=\"Les principales sources naturelles de calcium, animales et v\u00e9g\u00e9tales\" width=\"603\" height=\"337\" srcset=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2020\/03\/Calcium.webp 603w, https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2020\/03\/Calcium-300x168.webp 300w, https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2020\/03\/Calcium-600x335.webp 600w\" sizes=\"(max-width: 603px) 100vw, 603px\" \/><figcaption id=\"caption-attachment-16593\" class=\"wp-caption-text\">Les principales sources naturelles de calcium, animales et v\u00e9g\u00e9tales<\/figcaption><\/figure>\n<p><strong>Calcium<\/strong><\/p>\n<p>Le calcium est le min\u00e9ral le plus abondant dans le corps humain. Il se trouve principalement (99 %) dans les os et les dents. Le 1% restant est utilis\u00e9 dans les fluides corporels pour la r\u00e9gulation de la pression sanguine, la s\u00e9cr\u00e9tion d&rsquo;hormones, le mouvement musculaire et la fonction enzymatique. <\/p>\n<p><strong>Sources de calcium.<\/strong>  Le calcium est naturellement pr\u00e9sent dans de nombreux aliments. Les principales sources v\u00e9g\u00e9tales de calcium sont les l\u00e9gumes \u00e0 feuilles vertes (\u00e9pinards, chou fris\u00e9, brocoli), les l\u00e9gumineuses, les c\u00e9r\u00e9ales, les noix et les graines (amandes, s\u00e9same, chia). Les principales sources animales de calcium sont le lait et les produits laitiers, les poissons comme les sardines et le saumon, et les yaourts. De nombreux produits laitiers et jus de fruits sont \u00e9galement enrichis en calcium.   <\/p>\n<p><strong>Carence en calcium et pr\u00e9vention.<\/strong>  Le calcium est bien r\u00e9gul\u00e9 dans l&rsquo;organisme car il joue un r\u00f4le important dans les fonctions corporelles telles que la contraction musculaire et l&rsquo;activit\u00e9 nerveuse. Lorsque l&rsquo;organisme est pauvre en calcium, il doit puiser le calcium dans les os pour se r\u00e9approvisionner. Il peut en r\u00e9sulter une ost\u00e9omalacie ou une fragilit\u00e9 osseuse. La carence en calcium dans les os peut \u00e9galement r\u00e9sulter d&rsquo;un apport insuffisant en vitamine D, qui est vitale pour l&rsquo;absorption du calcium et son d\u00e9p\u00f4t dans les os. Les autres sympt\u00f4mes d&rsquo;une carence en calcium sont des probl\u00e8mes musculaires, de la fatigue, des probl\u00e8mes de peau et des probl\u00e8mes dentaires. Les carences en calcium peuvent \u00eatre \u00e9vit\u00e9es en consommant des aliments riches en calcium et en assurant une production ou une consommation suffisante de vitamine D.     <\/p>\n<p>La vitamine D et le calcium sont des micronutriments compl\u00e9mentaires en termes de fonctions et de besoins dans le corps humain. BioAnalyt ne propose pas actuellement de produit iCheck pour tester l&rsquo;un ou l&rsquo;autre de ces micronutriments, mais si la demande est suffisante, nous pourrons les ajouter \u00e0 notre programme de recherche. <\/p>\n<p>Dans la suite de cette s\u00e9rie, nous aborderons la <strong>vitamine E<\/strong> et le <strong>s\u00e9l\u00e9nium<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans ce num\u00e9ro de notre s\u00e9rie sur les vitamines et les min\u00e9raux, nous examinons de plus pr\u00e8s pourquoi la vitamine D et le calcium sont si importants, comment nous pouvons en obtenir suffisamment dans notre alimentation et comment pr\u00e9venir leurs carences !  <\/p>\n","protected":false},"author":6,"featured_media":20080,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1013,1023,1001,1098],"tags":[996,1037,1169,1170],"class_list":["post-22874","stories","type-stories","status-publish","has-post-thumbnail","hentry","category-blog-fr","category-etat-nutritionnel","category-general-fr","category-vitamines-et-mineraux","tag-bioanalyt-fr","tag-lalimentation","tag-le-calcium","tag-vitamine-d"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En savoir plus sur les vitamines et les min\u00e9raux : Vitamine D et calcium<\/title>\n<meta name=\"description\" content=\"Apprenez comment la vitamine D et le calcium soutiennent la sant\u00e9 des os, pr\u00e9viennent le rachitisme et l&#039;ost\u00e9oporose, et pourquoi leur synergie est vitale pour la croissance, la force et la fonction immunitaire.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bioanalyt.com\/fr\/stories\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En savoir plus sur les vitamines et les min\u00e9raux : Vitamine D et calcium\" \/>\n<meta property=\"og:description\" content=\"Apprenez comment la vitamine D et le calcium soutiennent la sant\u00e9 des os, pr\u00e9viennent le rachitisme et l&#039;ost\u00e9oporose, et pourquoi leur synergie est vitale pour la croissance, la force et la fonction immunitaire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bioanalyt.com\/fr\/stories\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\/\" \/>\n<meta property=\"og:site_name\" content=\"Bioanalyt\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2020\/03\/Vitamin-D.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\\\/\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\\\/\",\"name\":\"En savoir plus sur les vitamines et les min\u00e9raux : Vitamine D et calcium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Vitamin-D.webp\",\"datePublished\":\"2020-03-27T13:31:58+00:00\",\"description\":\"Apprenez comment la vitamine D et le calcium soutiennent la sant\u00e9 des os, pr\u00e9viennent le rachitisme et l'ost\u00e9oporose, et pourquoi leur synergie est vitale pour la croissance, la force et la fonction immunitaire.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Vitamin-D.webp\",\"contentUrl\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Vitamin-D.webp\",\"width\":480,\"height\":320,\"caption\":\"Vitamin D sources\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En savoir plus sur les vitamines et les min\u00e9raux : Vitamine D et calcium\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#website\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/\",\"name\":\"Bioanalyt\",\"description\":\"Measure for life\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bioanalyt.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#organization\",\"name\":\"Bioanalyt\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Logo-Horizontal.svg\",\"contentUrl\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Logo-Horizontal.svg\",\"width\":112,\"height\":64,\"caption\":\"Bioanalyt\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bioanalyt\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BioAnalyt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En savoir plus sur les vitamines et les min\u00e9raux : Vitamine D et calcium","description":"Apprenez comment la vitamine D et le calcium soutiennent la sant\u00e9 des os, pr\u00e9viennent le rachitisme et l'ost\u00e9oporose, et pourquoi leur synergie est vitale pour la croissance, la force et la fonction immunitaire.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bioanalyt.com\/fr\/stories\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\/","og_locale":"fr_FR","og_type":"article","og_title":"En savoir plus sur les vitamines et les min\u00e9raux : Vitamine D et calcium","og_description":"Apprenez comment la vitamine D et le calcium soutiennent la sant\u00e9 des os, pr\u00e9viennent le rachitisme et l'ost\u00e9oporose, et pourquoi leur synergie est vitale pour la croissance, la force et la fonction immunitaire.","og_url":"https:\/\/www.bioanalyt.com\/fr\/stories\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\/","og_site_name":"Bioanalyt","og_image":[{"width":480,"height":320,"url":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2020\/03\/Vitamin-D.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\/","url":"https:\/\/www.bioanalyt.com\/fr\/stories\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\/","name":"En savoir plus sur les vitamines et les min\u00e9raux : Vitamine D et calcium","isPartOf":{"@id":"https:\/\/www.bioanalyt.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\/#primaryimage"},"image":{"@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2020\/03\/Vitamin-D.webp","datePublished":"2020-03-27T13:31:58+00:00","description":"Apprenez comment la vitamine D et le calcium soutiennent la sant\u00e9 des os, pr\u00e9viennent le rachitisme et l'ost\u00e9oporose, et pourquoi leur synergie est vitale pour la croissance, la force et la fonction immunitaire.","breadcrumb":{"@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bioanalyt.com\/fr\/stories\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\/#primaryimage","url":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2020\/03\/Vitamin-D.webp","contentUrl":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2020\/03\/Vitamin-D.webp","width":480,"height":320,"caption":"Vitamin D sources"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/en-savoir-plus-sur-les-vitamines-et-les-mineraux-vitamine-d-et-calcium\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bioanalyt.com\/fr\/"},{"@type":"ListItem","position":2,"name":"En savoir plus sur les vitamines et les min\u00e9raux : Vitamine D et calcium"}]},{"@type":"WebSite","@id":"https:\/\/www.bioanalyt.com\/#website","url":"https:\/\/www.bioanalyt.com\/","name":"Bioanalyt","description":"Measure for life","publisher":{"@id":"https:\/\/www.bioanalyt.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bioanalyt.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.bioanalyt.com\/#organization","name":"Bioanalyt","url":"https:\/\/www.bioanalyt.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bioanalyt.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/09\/Logo-Horizontal.svg","contentUrl":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/09\/Logo-Horizontal.svg","width":112,"height":64,"caption":"Bioanalyt"},"image":{"@id":"https:\/\/www.bioanalyt.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/bioanalyt\/","https:\/\/www.youtube.com\/user\/BioAnalyt"]}]}},"_links":{"self":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/stories\/22874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/stories"}],"about":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/types\/stories"}],"author":[{"embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"version-history":[{"count":0,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/stories\/22874\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/media\/20080"}],"wp:attachment":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/media?parent=22874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/categories?post=22874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/tags?post=22874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}