{"id":22846,"date":"2022-11-17T18:28:14","date_gmt":"2022-11-17T18:28:14","guid":{"rendered":"https:\/\/www.bioanalyt.com\/stories\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\/"},"modified":"2022-11-17T18:28:14","modified_gmt":"2022-11-17T18:28:14","slug":"le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement","status":"publish","type":"stories","link":"https:\/\/www.bioanalyt.com\/fr\/stories\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\/","title":{"rendered":"Le triple fardeau de la malnutrition : Une menace pour la r\u00e9alisation des objectifs du Mill\u00e9naire pour le d\u00e9veloppement"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>Dans la complexit\u00e9 actuelle des syst\u00e8mes socio-\u00e9conomiques, la malnutrition a des effets en cascade sur les moyens d&rsquo;atteindre les objectifs de d\u00e9veloppement durable (ODD). La malnutrition, qui englobe la suralimentation, la sous-nutrition et la faim inapparente, est le r\u00e9sultat de syst\u00e8mes alimentaires non durables. <\/p>\n<p>Sur les 17 ODD, au moins 12 sont directement associ\u00e9s \u00e0 la nutrition. Il est d\u00e9sormais bien \u00e9tabli que l&rsquo;agenda 2030 ne pourra \u00eatre pleinement r\u00e9alis\u00e9 que si des investissements consid\u00e9rables, des solutions technologiques et des interventions politiques adapt\u00e9es sont mis en \u0153uvre pour lutter contre la malnutrition, \u00e9galement appel\u00e9e triple menace. <\/p>\n<figure id=\"attachment_16453\" aria-describedby=\"caption-attachment-16453\" style=\"width: 512px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-16453 size-full\" src=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2022\/11\/E_2018_SDG_Poster_without_UN_emblem_Letter-US-1024x791-1.webp\" alt=\"Objectifs de d\u00e9veloppement durable (ONU)\" width=\"512\" height=\"396\" srcset=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2022\/11\/E_2018_SDG_Poster_without_UN_emblem_Letter-US-1024x791-1.webp 512w, https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2022\/11\/E_2018_SDG_Poster_without_UN_emblem_Letter-US-1024x791-1-300x232.webp 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><figcaption id=\"caption-attachment-16453\" class=\"wp-caption-text\">Objectifs de d\u00e9veloppement durable (ONU)<\/figcaption><\/figure>\n<p>Le changement climatique a un impact consid\u00e9rable sur la productivit\u00e9 des terres agricoles et du b\u00e9tail. On estime que d&rsquo;ici 2050, les rendements des c\u00e9r\u00e9ales secondaires, des graines ol\u00e9agineuses, du bl\u00e9 et du riz auront diminu\u00e9 de 17 %. Il sera de plus en plus difficile de nourrir la population mondiale croissante avec des repas nutritifs. Selon le rapport de 2021 sur l&rsquo;\u00e9tat d&rsquo;avancement des objectifs du Mill\u00e9naire pour le d\u00e9veloppement, deux milliards de personnes souffrent de malnutrition dans le monde, ce qui expose un tiers de la population mondiale \u00e0 des risques de complications sanitaires.  <\/p>\n<p>Des recherches ont montr\u00e9 que l&rsquo;objectif de d\u00e9veloppement durable n\u00b0 12, qui vise \u00e0 garantir des modes de consommation et de production durables, est fortement compromis, car les soci\u00e9t\u00e9s sont confront\u00e9es \u00e0 une menace de suralimentation entra\u00eenant l&rsquo;ob\u00e9sit\u00e9 et des maladies non transmissibles. Il est essentiel de noter que l&rsquo;ob\u00e9sit\u00e9 n&rsquo;est plus l&rsquo;apanage des communaut\u00e9s \u00e0 hauts revenus, car les habitudes alimentaires d\u00e9s\u00e9quilibr\u00e9es sont \u00e9galement de plus en plus r\u00e9pandues dans les m\u00e9nages ruraux et \u00e0 faibles revenus. En outre, la suralimentation provoque plus de d\u00e9c\u00e8s que la sous-nutrition. Cette situation sabote directement les progr\u00e8s accomplis dans la r\u00e9alisation de l&rsquo;ODD 3.8, qui porte sur la sant\u00e9 et le bien-\u00eatre.   <\/p>\n<p>Les habitudes alimentaires non durables ont \u00e9galement une incidence sur l&rsquo;objectif de d\u00e9veloppement durable 2.2, qui vise \u00e0 mettre fin \u00e0 toutes les formes de malnutrition d&rsquo;ici \u00e0 2025, et sur l&rsquo;objectif de d\u00e9veloppement durable 2.4, qui se concentre sur la production alimentaire durable d&rsquo;ici \u00e0 2030.<\/p>\n<p>La pand\u00e9mie de covid-19 a eu des effets en cascade sur les progr\u00e8s des objectifs de d\u00e9veloppement durable 8 et 9, qui pr\u00e9voient des emplois d\u00e9cents pour tous et le d\u00e9veloppement d&rsquo;infrastructures r\u00e9silientes. L&rsquo;absence de moyens \u00e9conomiques durables et r\u00e9sistants a pouss\u00e9 environ 132 millions de personnes vers la sous-alimentation chronique et la faim inapparente. <\/p>\n<p>La situation \u00e9tait d\u00e9j\u00e0 d\u00e9sastreuse en 2019, car environ 690 millions de personnes dans le monde ont souffert de la faim. La sous-alimentation et la faim menacent souvent les couches les plus vuln\u00e9rables de la soci\u00e9t\u00e9, mettant directement en \u00e9vidence les \u00e9carts dans la r\u00e9alisation de l&rsquo;objectif 1 de l&rsquo;ODD visant \u00e0 mettre fin \u00e0 la pauvret\u00e9. Actuellement, 149,2 millions d&rsquo;enfants de moins de cinq ans souffrent d&rsquo;un retard de croissance et environ 45 % de la mortalit\u00e9 infantile est due \u00e0 la malnutrition. Ces chiffres compromettent gravement l&rsquo;objectif 3 de l&rsquo;ODD, qui vise \u00e0 assurer une vie saine et le bien-\u00eatre de tous les groupes d&rsquo;\u00e2ge.   <\/p>\n<p>&nbsp;<\/p>\n<p>De m\u00eame, les femmes et les filles des pays en d\u00e9veloppement adoptent souvent des habitudes alimentaires de mauvaise qualit\u00e9 et n&rsquo;ont pas acc\u00e8s \u00e0 des aliments nutritifs en raison des pr\u00e9jug\u00e9s sexistes. Il en r\u00e9sulte une faim inapparente qui compromet l&rsquo;objectif de d\u00e9veloppement durable n\u00b0 5, qui vise \u00e0 r\u00e9aliser l&rsquo;\u00e9galit\u00e9 des sexes, et l&rsquo;objectif de d\u00e9veloppement durable n\u00b0 10, qui porte sur la r\u00e9duction des in\u00e9galit\u00e9s. <\/p>\n<p>En conclusion, les chercheurs en sciences sociales ont soulign\u00e9 la n\u00e9cessit\u00e9 d&rsquo;\u00e9viter de travailler en silos sectoriels et de d\u00e9velopper des approches transversales et des m\u00e9canismes de coordination \u00e0 tous les niveaux pour r\u00e9aliser les ODD.<\/p>\n<h3><strong>Comment BioAnalyt contribue \u00e0 la mise en place de syst\u00e8mes alimentaires durables<\/strong><\/h3>\n<p>Les appareils iCheck de BioAnalyt ont \u00e9t\u00e9 d\u00e9velopp\u00e9s pour rendre les tests alimentaires plus rapides, mobiles et moins chers, ce qui est l&rsquo;une des exigences essentielles pour des programmes de fortification efficaces afin de lutter contre la malnutrition. Chez BioAnalyt, nous avons \u00e9galement d\u00e9velopp\u00e9 iCheck Connect, une plateforme num\u00e9rique con\u00e7ue pour analyser et visualiser les donn\u00e9es et les mesures de contr\u00f4le de la qualit\u00e9 \u00e0 partir de n&rsquo;importe quel appareil iCheck. <\/p>\n<p>Un projet pilote avec Nutrition International et FORTIS explorant et testant la facilit\u00e9 d&rsquo;utilisation d&rsquo;iCheck Connect est \u00e9galement en cours. Dans ce projet, le logiciel iCheckConnect est utilis\u00e9 pour g\u00e9n\u00e9rer et sauvegarder les donn\u00e9es des producteurs d&rsquo;huile fortifi\u00e9e et des inspecteurs alimentaires au Pakistan dans le cadre de leur processus de contr\u00f4le et de surveillance de la qualit\u00e9. L&rsquo;id\u00e9e est de fournir un acc\u00e8s instantan\u00e9 aux donn\u00e9es de fortification pour les parties prenantes concern\u00e9es \u00e0 tous les niveaux, qui peuvent ensuite \u00eatre utilis\u00e9es pour am\u00e9liorer la prise de d\u00e9cision. Le d\u00e9veloppement de la plateforme iCheck Connect est soutenu par l&rsquo;Acc\u00e9l\u00e9rateur d&rsquo;innovation du Programme alimentaire mondial et par le BMGF.   <\/p>\n<p>Les synergies de BioAnalyt se d\u00e9veloppent \u00e9galement en coop\u00e9ration avec TechnoServe et sa plateforme <em>Micronutrient Fortification Index<\/em> (MFI) lanc\u00e9e avec l&rsquo;industrie alimentaire au Nig\u00e9ria. BioAnalyt continuera \u00e0 d\u00e9velopper ses collaborations sur la connectivit\u00e9 automatis\u00e9e avec d&rsquo;autres plateformes de donn\u00e9es, telles que FortifyMIS (dirig\u00e9e par GAIN et FFI), PalmATrack (dirig\u00e9e par Millhouse), et le Global Fortification Data Exchange (GFDx). Cela permettra aux parties prenantes de disposer des bonnes donn\u00e9es au bon moment pour prendre les meilleures d\u00e9cisions afin d&rsquo;assurer la r\u00e9ussite des programmes de fortification.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sur les 17 ODD, au moins 12 sont directement associ\u00e9s \u00e0 la nutrition. Il est d\u00e9sormais bien \u00e9tabli que l&rsquo;agenda 2030 ne pourra \u00eatre pleinement r\u00e9alis\u00e9 que si des investissements consid\u00e9rables, des solutions technologiques et des interventions politiques adapt\u00e9es sont mis en \u0153uvre pour lutter contre la malnutrition, \u00e9galement appel\u00e9e triple menace. <\/p>\n","protected":false},"author":8,"featured_media":19062,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1013,1124,1001,1115],"tags":[1127,993,1126,1114,1125],"class_list":["post-22846","stories","type-stories","status-publish","has-post-thumbnail","hentry","category-blog-fr","category-des-moulins-pour-la-nutrition-fr","category-general-fr","category-nutrition-mondiale","tag-developpement-durable","tag-lenrichissement-des-aliments","tag-le-changement-climatique","tag-malnutrition-fr","tag-technologie-alimentaire"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le triple fardeau de la malnutrition : Une menace pour la r\u00e9alisation des objectifs du Mill\u00e9naire pour le d\u00e9veloppement<\/title>\n<meta name=\"description\" content=\"Le triple fardeau de la malnutrition - sous-nutrition, surnutrition et faim inapparente - compromet les progr\u00e8s vers la r\u00e9alisation des objectifs de d\u00e9veloppement durable.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bioanalyt.com\/fr\/stories\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le triple fardeau de la malnutrition : Une menace pour la r\u00e9alisation des objectifs du Mill\u00e9naire pour le d\u00e9veloppement\" \/>\n<meta property=\"og:description\" content=\"Le triple fardeau de la malnutrition - sous-nutrition, surnutrition et faim inapparente - compromet les progr\u00e8s vers la r\u00e9alisation des objectifs de d\u00e9veloppement durable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bioanalyt.com\/fr\/stories\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\/\" \/>\n<meta property=\"og:site_name\" content=\"Bioanalyt\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2022\/11\/12-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\\\/\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\\\/\",\"name\":\"Le triple fardeau de la malnutrition : Une menace pour la r\u00e9alisation des objectifs du Mill\u00e9naire pour le d\u00e9veloppement\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/12-scaled.jpg\",\"datePublished\":\"2022-11-17T18:28:14+00:00\",\"description\":\"Le triple fardeau de la malnutrition - sous-nutrition, surnutrition et faim inapparente - compromet les progr\u00e8s vers la r\u00e9alisation des objectifs de d\u00e9veloppement durable.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/12-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/12-scaled.jpg\",\"width\":2560,\"height\":1280,\"caption\":\"xr:d:DAFMS8Dcbzw:8,j:41383911467,t:22111812\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le triple fardeau de la malnutrition : Une menace pour la r\u00e9alisation des objectifs du Mill\u00e9naire pour le d\u00e9veloppement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#website\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/\",\"name\":\"Bioanalyt\",\"description\":\"Measure for life\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bioanalyt.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#organization\",\"name\":\"Bioanalyt\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Logo-Horizontal.svg\",\"contentUrl\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Logo-Horizontal.svg\",\"width\":112,\"height\":64,\"caption\":\"Bioanalyt\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bioanalyt\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BioAnalyt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le triple fardeau de la malnutrition : Une menace pour la r\u00e9alisation des objectifs du Mill\u00e9naire pour le d\u00e9veloppement","description":"Le triple fardeau de la malnutrition - sous-nutrition, surnutrition et faim inapparente - compromet les progr\u00e8s vers la r\u00e9alisation des objectifs de d\u00e9veloppement durable.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bioanalyt.com\/fr\/stories\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\/","og_locale":"fr_FR","og_type":"article","og_title":"Le triple fardeau de la malnutrition : Une menace pour la r\u00e9alisation des objectifs du Mill\u00e9naire pour le d\u00e9veloppement","og_description":"Le triple fardeau de la malnutrition - sous-nutrition, surnutrition et faim inapparente - compromet les progr\u00e8s vers la r\u00e9alisation des objectifs de d\u00e9veloppement durable.","og_url":"https:\/\/www.bioanalyt.com\/fr\/stories\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\/","og_site_name":"Bioanalyt","og_image":[{"width":2560,"height":1280,"url":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2022\/11\/12-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\/","url":"https:\/\/www.bioanalyt.com\/fr\/stories\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\/","name":"Le triple fardeau de la malnutrition : Une menace pour la r\u00e9alisation des objectifs du Mill\u00e9naire pour le d\u00e9veloppement","isPartOf":{"@id":"https:\/\/www.bioanalyt.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\/#primaryimage"},"image":{"@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2022\/11\/12-scaled.jpg","datePublished":"2022-11-17T18:28:14+00:00","description":"Le triple fardeau de la malnutrition - sous-nutrition, surnutrition et faim inapparente - compromet les progr\u00e8s vers la r\u00e9alisation des objectifs de d\u00e9veloppement durable.","breadcrumb":{"@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bioanalyt.com\/fr\/stories\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\/#primaryimage","url":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2022\/11\/12-scaled.jpg","contentUrl":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2022\/11\/12-scaled.jpg","width":2560,"height":1280,"caption":"xr:d:DAFMS8Dcbzw:8,j:41383911467,t:22111812"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/le-triple-fardeau-de-la-malnutrition-une-menace-pour-la-realisation-des-objectifs-du-millenaire-pour-le-developpement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bioanalyt.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le triple fardeau de la malnutrition : Une menace pour la r\u00e9alisation des objectifs du Mill\u00e9naire pour le d\u00e9veloppement"}]},{"@type":"WebSite","@id":"https:\/\/www.bioanalyt.com\/#website","url":"https:\/\/www.bioanalyt.com\/","name":"Bioanalyt","description":"Measure for life","publisher":{"@id":"https:\/\/www.bioanalyt.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bioanalyt.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.bioanalyt.com\/#organization","name":"Bioanalyt","url":"https:\/\/www.bioanalyt.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bioanalyt.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/09\/Logo-Horizontal.svg","contentUrl":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/09\/Logo-Horizontal.svg","width":112,"height":64,"caption":"Bioanalyt"},"image":{"@id":"https:\/\/www.bioanalyt.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/bioanalyt\/","https:\/\/www.youtube.com\/user\/BioAnalyt"]}]}},"_links":{"self":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/stories\/22846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/stories"}],"about":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/types\/stories"}],"author":[{"embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":0,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/stories\/22846\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/media\/19062"}],"wp:attachment":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/media?parent=22846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/categories?post=22846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/tags?post=22846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}