{"id":22845,"date":"2022-09-23T14:58:38","date_gmt":"2022-09-23T14:58:38","guid":{"rendered":"https:\/\/www.bioanalyt.com\/stories\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\/"},"modified":"2022-09-23T14:58:38","modified_gmt":"2022-09-23T14:58:38","slug":"renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification","status":"publish","type":"stories","link":"https:\/\/www.bioanalyt.com\/fr\/stories\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\/","title":{"rendered":"Renforcer les synergies pour assurer la r\u00e9ussite des projets de fortification"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>Florian J. Schweigert, fondateur et directeur g\u00e9n\u00e9ral de BioAnalyt, a particip\u00e9 au sommet Business Fights Poverty Global Goals qui s&rsquo;est tenu \u00e0 l&rsquo;Assembl\u00e9e g\u00e9n\u00e9rale des Nations Unies en d\u00e9but de semaine. Une vingtaine d&rsquo;experts du secteur de l&rsquo;alimentation et de la nutrition se sont r\u00e9unis en personne et virtuellement \u00e0 New York pour discuter de la mani\u00e8re dont les innovations technologiques et les partenariats peuvent tirer le meilleur parti des projets de fortification alimentaire \u00e0 grande \u00e9chelle (LSFF). <\/p>\n<p>Parmi les points essentiels \u00e0 l&rsquo;ordre du jour de la discussion, citons l&rsquo;utilisation de solutions num\u00e9riques et d&rsquo;innovations technologiques pour promouvoir l&rsquo;enrichissement \u00e0 petite \u00e9chelle, l&rsquo;offre d&rsquo;aliments enrichis \u00e0 un plus grand nombre de personnes, l&rsquo;\u00e9valuation des possibilit\u00e9s de partenariats public-priv\u00e9 et la recherche d&rsquo;opportunit\u00e9s d&rsquo;investissement au niveau national pour d\u00e9velopper les projets d&rsquo;enrichissement.<\/p>\n<p>Au niveau mondial, on estime qu&rsquo;environ la moiti\u00e9 des aliments pr\u00e9tendument enrichis ne contiennent pas les quantit\u00e9s ad\u00e9quates de micronutriments stipul\u00e9es dans les normes nationales. Selon le professeur Schweigert, quatre facteurs principaux contribuent \u00e0 ce probl\u00e8me : <\/p>\n<ul>\n<li>Le manque de confiance et de compr\u00e9hension mutuelle entre l&rsquo;industrie alimentaire et les organismes de r\u00e9glementation.<\/li>\n<li>Le manque de capacit\u00e9 r\u00e9glementaire, y compris en mati\u00e8re d&rsquo;essais alimentaires.<\/li>\n<li>L&rsquo;absence de soutien, de sanctions et d&rsquo;incitations appropri\u00e9s pour garantir le respect des normes et des r\u00e9glementations.<\/li>\n<li>Difficult\u00e9s \u00e0 obtenir des intrants de fortification rentables, tels que les mati\u00e8res premi\u00e8res, les pr\u00e9m\u00e9langes et l&rsquo;\u00e9quipement.<\/li>\n<\/ul>\n<p>Une plus grande facilit\u00e9 et pr\u00e9cision dans la collecte des donn\u00e9es et une plus grande transparence dans le partage et l&rsquo;analyse des donn\u00e9es peuvent contribuer \u00e0 soutenir les programmes de fortification\u00a0\u00bb, d\u00e9clare le professeur Schweigert.<\/p>\n<p>Selon les experts du syst\u00e8me alimentaire, la num\u00e9risation du continuum de donn\u00e9es, de la collecte \u00e0 l&rsquo;interpr\u00e9tation, l&rsquo;analyse et la communication, peut permettre d&rsquo;optimiser le temps et les ressources, tant pour les organismes de r\u00e9glementation que pour les agences de sant\u00e9 de plus en plus pr\u00e9occup\u00e9es par la crise de l&rsquo;approvisionnement alimentaire exacerb\u00e9e par le COVID-19.<\/p>\n<p>Parlant de la contribution de BioAnalyt aux solutions num\u00e9riques et technologiques visant \u00e0 am\u00e9liorer la fortification des aliments, le professeur Schweigert explique qu&rsquo;en plus de notre devise qui est de rendre les tests alimentaires plus rapides, mobiles et moins chers, BioAnalyt a d\u00e9velopp\u00e9 iCheck Connect, qui peut am\u00e9liorer la transparence et la capacit\u00e9 d&rsquo;action des syst\u00e8mes de collecte de donn\u00e9es d&rsquo;assurance et de contr\u00f4le de la qualit\u00e9 (AQ &amp; CQ). iCheck Connect est une plateforme num\u00e9rique d\u00e9velopp\u00e9e pour analyser et visualiser les donn\u00e9es et les mesures de contr\u00f4le de la qualit\u00e9 \u00e0 partir de n&rsquo;importe quel appareil iCheck. <\/p>\n<p>Un projet pilote avec Nutrition International et FORTIS explorant et testant la facilit\u00e9 d&rsquo;utilisation d&rsquo;iCheck Connect est \u00e9galement en cours. Dans le cadre de ce projet, le logiciel iCheckConnect est utilis\u00e9 pour g\u00e9n\u00e9rer et enregistrer des donn\u00e9es provenant des producteurs d&rsquo;huile et des inspecteurs des denr\u00e9es alimentaires au Pakistan, dans le cadre de leur processus de contr\u00f4le et de surveillance de la qualit\u00e9. L&rsquo;id\u00e9e est de fournir un acc\u00e8s instantan\u00e9 aux donn\u00e9es de fortification pour les parties prenantes concern\u00e9es \u00e0 tous les niveaux, qui peuvent ensuite \u00eatre utilis\u00e9es pour am\u00e9liorer la prise de d\u00e9cision. Le d\u00e9veloppement de la plateforme iCheck Connect est soutenu par l&rsquo;Acc\u00e9l\u00e9rateur d&rsquo;innovation du Programme alimentaire mondial et par le BMGF.   <\/p>\n<p>En outre, BioAnalyt propose \u00e9galement des formations pour s&rsquo;assurer que les processus d&rsquo;\u00e9chantillonnage et de mesure sont effectu\u00e9s correctement, avec des r\u00e9sultats pr\u00e9cis et fiables, r\u00e9duisant ainsi le risque d&rsquo;erreur humaine.<\/p>\n<p>Les synergies de BioAnalyt se d\u00e9veloppent \u00e9galement en coop\u00e9ration avec TechnoServe et sa plateforme <em>Micronutrient Fortification Index<\/em> (MFI) lanc\u00e9e avec l&rsquo;industrie alimentaire au Nig\u00e9ria. BioAnalyt continuera \u00e0 d\u00e9velopper ses collaborations sur la connectivit\u00e9 automatis\u00e9e avec d&rsquo;autres plateformes de donn\u00e9es, telles que FortifyMIS (dirig\u00e9e par GAIN et FFI), PalmATrack (dirig\u00e9e par Millhouse), et le Global Fortification Data Exchange (GFDx). Cela permettra aux parties prenantes de disposer des bonnes donn\u00e9es au bon moment pour prendre les meilleures d\u00e9cisions afin d&rsquo;assurer la r\u00e9ussite des programmes de fortification.  <\/p>\n<p>En ce qui concerne les enseignements tir\u00e9s de son travail sur les plateformes de donn\u00e9es num\u00e9riques susmentionn\u00e9es, le professeur Schweigert indique qu&rsquo;il ne suffit pas de d\u00e9velopper et de num\u00e9riser les processus d&rsquo;assurance et de contr\u00f4le de la qualit\u00e9.<\/p>\n<p>Au contraire, il faut consacrer davantage de temps et d&rsquo;efforts concert\u00e9s \u00e0 la conception d&rsquo;outils selon une approche ascendante, en gardant \u00e0 l&rsquo;esprit le point de vue de l&rsquo;utilisateur, tout en garantissant une formation continue et une sensibilisation \u00e0 l&rsquo;utilisation de ces technologies\u00a0\u00bb, ajoute-t-il.<\/p>\n<p>Pour r\u00e9ussir \u00e0 num\u00e9riser les donn\u00e9es et les aspects de contr\u00f4le de la qualit\u00e9 des programmes de fortification, les experts ont soulign\u00e9 \u00e0 plusieurs reprises l&rsquo;importance de s&rsquo;assurer que les outils num\u00e9riques sont conviviaux, adapt\u00e9s \u00e0 l&rsquo;objectif et qu&rsquo;ils peuvent r\u00e9duire les co\u00fbts et la charge de travail. Il est \u00e9galement n\u00e9cessaire de d\u00e9velopper d&rsquo;autres solutions technologiques en tenant compte des d\u00e9fis \u00e0 relever au niveau national, comme l&rsquo;analyse facile et fiable des pr\u00e9m\u00e9langes et des aliments enrichis en fonction d&rsquo;indicateurs et de tendances en mati\u00e8re de nutrition et de sant\u00e9, sur la base de l&rsquo;\u00e9chantillon de population. <\/p>\n<p>Toutefois, selon le professeur Schweigert, l&rsquo;obtention de donn\u00e9es de bonne qualit\u00e9 g\u00e9n\u00e9r\u00e9es par du mat\u00e9riel adapt\u00e9 et accessible, puis l&rsquo;introduction de ces donn\u00e9es dans les technologies num\u00e9riques restent un obstacle important. La fourniture durable d&rsquo;un soutien personnalis\u00e9 aux parties prenantes locales est la cl\u00e9 de l&rsquo;am\u00e9lioration de l&rsquo;impact et de la conformit\u00e9. <\/p>\n<p>Selon le professeur Schweigert, l&rsquo;investissement dans les structures, les institutions et les prestataires de services au-del\u00e0 des cycles de financement quinquennaux est un autre domaine sur lequel il faut travailler.<\/p>\n<p>Par exemple, BioAnalyt est actuellement dans la phase initiale de lancement de QuIMPACT, une organisation \u00e0 but non lucratif qui pr\u00e9voit de fournir un soutien continu au-del\u00e0 des cycles de financement quinquennaux habituels et de servir de centre de connaissances sur tous les aspects techniques pour les parties prenantes internationales et locales, ajoute-t-il.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le fondateur et directeur g\u00e9n\u00e9ral de BioAnalyt, le professeur Dr Florian J. Schweigert, a particip\u00e9 au sommet Business Fights Poverty Global Goals qui s&rsquo;est tenu \u00e0 l&rsquo;Assembl\u00e9e g\u00e9n\u00e9rale des Nations Unies pour discuter de la mani\u00e8re dont les innovations technologiques et les partenariats peuvent tirer le meilleur parti des projets de fortification alimentaire \u00e0 grande \u00e9chelle (LSFF).<\/p>\n","protected":false},"author":8,"featured_media":19063,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1013,1067,990,1001],"tags":[1068,996,1048,1047,1017,1029,1037,993,1018,1050,1002,1049],"class_list":["post-22845","stories","type-stories","status-publish","has-post-thumbnail","hentry","category-blog-fr","category-couverture-de-lenrichissement-des-aliments","category-fortification-des-aliments","category-general-fr","tag-aliments-enrichis","tag-bioanalyt-fr","tag-conformite","tag-controle-alimentaire","tag-formation","tag-icheck-connect-fr","tag-lalimentation","tag-lenrichissement-des-aliments","tag-la-qualite-des-aliments","tag-la-securite-alimentaire","tag-les-carences-en-micronutriments","tag-systemes-de-donnees"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Renforcer les synergies pour assurer la r\u00e9ussite des projets de fortification - Bioanalyt<\/title>\n<meta name=\"description\" content=\"BioAnalyt se joint au Global Goals Summit pour discuter de l&#039;augmentation de l&#039;enrichissement des aliments gr\u00e2ce \u00e0 des outils num\u00e9riques comme iCheck Connect et des partenariats \u00e0 long terme comme QuImpact.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bioanalyt.com\/fr\/stories\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Renforcer les synergies pour assurer la r\u00e9ussite des projets de fortification - Bioanalyt\" \/>\n<meta property=\"og:description\" content=\"BioAnalyt se joint au Global Goals Summit pour discuter de l&#039;augmentation de l&#039;enrichissement des aliments gr\u00e2ce \u00e0 des outils num\u00e9riques comme iCheck Connect et des partenariats \u00e0 long terme comme QuImpact.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bioanalyt.com\/fr\/stories\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\/\" \/>\n<meta property=\"og:site_name\" content=\"Bioanalyt\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2022\/09\/photos-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\\\/\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\\\/\",\"name\":\"Renforcer les synergies pour assurer la r\u00e9ussite des projets de fortification - Bioanalyt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/photos-.jpg\",\"datePublished\":\"2022-09-23T14:58:38+00:00\",\"description\":\"BioAnalyt se joint au Global Goals Summit pour discuter de l'augmentation de l'enrichissement des aliments gr\u00e2ce \u00e0 des outils num\u00e9riques comme iCheck Connect et des partenariats \u00e0 long terme comme QuImpact.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/photos-.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/photos-.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Business Fights Poverty - Global Goals Summit\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/stories\\\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Renforcer les synergies pour assurer la r\u00e9ussite des projets de fortification\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#website\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/\",\"name\":\"Bioanalyt\",\"description\":\"Measure for life\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bioanalyt.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#organization\",\"name\":\"Bioanalyt\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Logo-Horizontal.svg\",\"contentUrl\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Logo-Horizontal.svg\",\"width\":112,\"height\":64,\"caption\":\"Bioanalyt\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bioanalyt\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BioAnalyt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Renforcer les synergies pour assurer la r\u00e9ussite des projets de fortification - Bioanalyt","description":"BioAnalyt se joint au Global Goals Summit pour discuter de l'augmentation de l'enrichissement des aliments gr\u00e2ce \u00e0 des outils num\u00e9riques comme iCheck Connect et des partenariats \u00e0 long terme comme QuImpact.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bioanalyt.com\/fr\/stories\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\/","og_locale":"fr_FR","og_type":"article","og_title":"Renforcer les synergies pour assurer la r\u00e9ussite des projets de fortification - Bioanalyt","og_description":"BioAnalyt se joint au Global Goals Summit pour discuter de l'augmentation de l'enrichissement des aliments gr\u00e2ce \u00e0 des outils num\u00e9riques comme iCheck Connect et des partenariats \u00e0 long terme comme QuImpact.","og_url":"https:\/\/www.bioanalyt.com\/fr\/stories\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\/","og_site_name":"Bioanalyt","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2022\/09\/photos-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\/","url":"https:\/\/www.bioanalyt.com\/fr\/stories\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\/","name":"Renforcer les synergies pour assurer la r\u00e9ussite des projets de fortification - Bioanalyt","isPartOf":{"@id":"https:\/\/www.bioanalyt.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\/#primaryimage"},"image":{"@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2022\/09\/photos-.jpg","datePublished":"2022-09-23T14:58:38+00:00","description":"BioAnalyt se joint au Global Goals Summit pour discuter de l'augmentation de l'enrichissement des aliments gr\u00e2ce \u00e0 des outils num\u00e9riques comme iCheck Connect et des partenariats \u00e0 long terme comme QuImpact.","breadcrumb":{"@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bioanalyt.com\/fr\/stories\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\/#primaryimage","url":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2022\/09\/photos-.jpg","contentUrl":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2022\/09\/photos-.jpg","width":1920,"height":1080,"caption":"Business Fights Poverty - Global Goals Summit"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bioanalyt.com\/fr\/stories\/renforcer-les-synergies-pour-assurer-la-reussite-des-projets-de-fortification\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bioanalyt.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Renforcer les synergies pour assurer la r\u00e9ussite des projets de fortification"}]},{"@type":"WebSite","@id":"https:\/\/www.bioanalyt.com\/#website","url":"https:\/\/www.bioanalyt.com\/","name":"Bioanalyt","description":"Measure for life","publisher":{"@id":"https:\/\/www.bioanalyt.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bioanalyt.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.bioanalyt.com\/#organization","name":"Bioanalyt","url":"https:\/\/www.bioanalyt.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bioanalyt.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/09\/Logo-Horizontal.svg","contentUrl":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/09\/Logo-Horizontal.svg","width":112,"height":64,"caption":"Bioanalyt"},"image":{"@id":"https:\/\/www.bioanalyt.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/bioanalyt\/","https:\/\/www.youtube.com\/user\/BioAnalyt"]}]}},"_links":{"self":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/stories\/22845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/stories"}],"about":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/types\/stories"}],"author":[{"embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":0,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/stories\/22845\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/media\/19063"}],"wp:attachment":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/media?parent=22845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/categories?post=22845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/tags?post=22845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}