{"id":22523,"date":"2024-10-16T09:34:18","date_gmt":"2024-10-16T09:34:18","guid":{"rendered":"https:\/\/www.bioanalyt.com\/carriere\/"},"modified":"2025-12-18T07:53:19","modified_gmt":"2025-12-18T07:53:19","slug":"carriere","status":"publish","type":"page","link":"https:\/\/www.bioanalyt.com\/fr\/carriere\/","title":{"rendered":"Carri\u00e8re"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"22523\" class=\"elementor elementor-22523 elementor-1111\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d7cb19b breadcrumb-top e-flex e-con-boxed e-con e-parent\" data-id=\"d7cb19b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cba8274 elementor-widget elementor-widget-heading\" data-id=\"cba8274\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Entreprise  <\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a59544 elementor-widget elementor-widget-image\" data-id=\"3a59544\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"24\" height=\"24\" src=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/10\/right-arrow-menu.svg\" class=\"attachment-full size-full wp-image-18573\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dc30f5 elementor-widget elementor-widget-heading\" data-id=\"5dc30f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Carri\u00e8re<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d8be07 e-flex e-con-boxed e-con e-parent\" data-id=\"1d8be07\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b4273c7 e-con-full e-flex e-con e-child\" data-id=\"b4273c7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f6c696e elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-heading\" data-id=\"f6c696e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Pr\u00eat \u00e0 commencer ?<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8e7ba5 elementor-widget elementor-widget-heading\" data-id=\"d8e7ba5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Rejoindre <strong>notre \u00e9quipe<\/strong><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97f176e elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"97f176e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#open-position\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir les postes \u00e0 pourvoir<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b7614de e-flex e-con-boxed e-con e-parent\" data-id=\"b7614de\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-28d171f elementor-arrows-position-outside career-slider elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"28d171f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;slides_to_show_mobile&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/10\/image-1.jpg\" alt=\"image-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2025\/02\/career-slider-final.webp\" alt=\"career-slider-final\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/10\/image-3.jpg\" alt=\"image-3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f40f398 e-flex e-con-boxed e-con e-parent\" data-id=\"f40f398\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-249413c e-con-full e-flex e-con e-child\" data-id=\"249413c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9189488 elementor-widget elementor-widget-heading\" data-id=\"9189488\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Espace de travail et culture<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a33f5d9 elementor-widget elementor-widget-text-editor\" data-id=\"a33f5d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chez BioAnalyt, vous ferez partie d&rsquo;une \u00e9quipe agile et comp\u00e9tente qui collabore au-del\u00e0 des silos pour avoir un impact r\u00e9el. Nous sommes une \u00e9quipe internationale compos\u00e9e de plus de 10 nationalit\u00e9s et nous croyons aux lignes de communication courtes. Nous encourageons la pens\u00e9e innovante et l&rsquo;autonomie. <\/p><p>Cette dynamique nous permet d&rsquo;\u00e9tablir des partenariats avec des gouvernements et des organisations du monde entier afin de d\u00e9ployer des solutions dans les zones o\u00f9 les besoins sont les plus importants. Notre engagement en faveur de solutions durables et \u00e9volutives nous permet d&rsquo;atteindre des environnements o\u00f9 les ressources sont limit\u00e9es et de combler le foss\u00e9 entre la connaissance et l&rsquo;action afin de rem\u00e9dier aux carences en vitamines et en min\u00e9raux \u00e0 grande \u00e9chelle. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ef623ee e-con-full e-flex e-con e-child\" data-id=\"ef623ee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9834ab9 elementor-widget elementor-widget-heading\" data-id=\"9834ab9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Pr\u00eat \u00e0 contribuer \u00e0 un changement significatif et \u00e0 avoir un impact mondial ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65cc502 elementor-widget elementor-widget-text-editor\" data-id=\"65cc502\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Oubliez la blouse de laboratoire ! Nos appareils iCheck font tourner les t\u00eates et facilitent l&rsquo;analyse des nutriments. Et devinez quoi ? Le monde entier l&rsquo;a remarqu\u00e9. Des plus grandes universit\u00e9s aux organisations les plus puissantes, nous travaillons en partenariat avec des organisations de premier plan \u00e0 l&rsquo;\u00e9chelle mondiale.    <\/p><p>Vous plongez dans le monde de l&rsquo;enrichissement des aliments ? Nous aussi ! Avec des normes de qualit\u00e9 in\u00e9gal\u00e9es et des objectifs ambitieux, nous ne nous contentons pas de participer \u00e0 la conversation sur la nutrition mondiale, nous la menons.    <\/p><p>Pr\u00eat \u00e0 laisser une trace dans l&rsquo;univers ? Rejoignez notre \u00e9quipe BioAnalyt. Plongez dans un monde o\u00f9 la passion rencontre l&rsquo;objectif et o\u00f9 chaque jour est un pas de plus vers un monde plus sain et mieux inform\u00e9.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-078725e elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"078725e\" data-element_type=\"container\" data-e-type=\"container\" id=\"open-position\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f30374b elementor-widget elementor-widget-heading\" data-id=\"f30374b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Postes \u00e0 pourvoir<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd8ef55 elementor-grid-1 elementor-posts--thumbnail-none elementor-widget__width-initial elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-posts\" data-id=\"fd8ef55\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:22,&quot;sizes&quot;:[]},&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-22677 personioposition type-personioposition status-publish hentry\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.bioanalyt.com\/fr\/?p=22677\" >\n\t\t\t\tResponsable de production et de montage*in (m\/w\/d) &#8211; Elektronik\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.bioanalyt.com\/fr\/?p=22677\" aria-label=\"En savoir plus sur Responsable de production et de montage*in (m\/w\/d) &#8211; Elektronik\" tabindex=\"-1\" >\n\t\t\tPlus d'informations \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-22009 personioposition type-personioposition status-publish hentry\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.bioanalyt.com\/?p=22009\" >\n\t\t\t\tProduktions- und Montagemitarbeiter*in (m\/w\/d) \u2013 Elektronik\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.bioanalyt.com\/?p=22009\" aria-label=\"En savoir plus sur Produktions- und Montagemitarbeiter*in (m\/w\/d) \u2013 Elektronik\" tabindex=\"-1\" >\n\t\t\tPlus d'informations \"\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7798e64 e-flex e-con-boxed e-con e-parent\" data-id=\"7798e64\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6a7a718 e-con-full e-flex e-con e-child\" data-id=\"6a7a718\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-696812e elementor-widget elementor-widget-heading\" data-id=\"696812e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prix et m\u00e9dias<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76140a9 elementor-widget elementor-widget-image-carousel\" data-id=\"76140a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;8&quot;,&quot;slides_to_show_tablet&quot;:&quot;6&quot;,&quot;slides_to_show_mobile&quot;:&quot;3&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/10\/logo-1-1.png\" alt=\"logo-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/10\/logo-2-1.png\" alt=\"logo-2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/10\/logo-3-1.png\" alt=\"logo-3\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/10\/logo-4-1.png\" alt=\"logo-4\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/10\/logo-5-1.png\" alt=\"logo-5\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/10\/logo-6-1.png\" alt=\"logo-6\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 sur 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/10\/logo-7.png\" alt=\"logo-7\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 sur 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/10\/logo-8.png\" alt=\"logo-8\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a47b2a8 e-flex e-con-boxed e-con e-parent\" data-id=\"a47b2a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8d1aa76 e-con-full e-flex e-con e-child\" data-id=\"8d1aa76\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ef9b17 elementor-widget elementor-widget-heading\" data-id=\"4ef9b17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Localisation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-523a93d e-con-full e-flex e-con e-child\" data-id=\"523a93d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-baa52e9 elementor-widget__width-inherit elementor-widget elementor-widget-google_maps\" data-id=\"baa52e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Rheinstra%C3%9Fe%2017%2C%2014513%20Teltow%2C%20Germany&#038;t=m&#038;z=15&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Rheinstra\u00dfe 17, 14513 Teltow, Germany\"\n\t\t\t\t\taria-label=\"Rheinstra\u00dfe 17, 14513 Teltow, Germany\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1017c9f e-con-full map-address e-flex e-con e-child\" data-id=\"1017c9f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;position&quot;:&quot;absolute&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e482a4 elementor-widget elementor-widget-heading\" data-id=\"8e482a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Bioanalyt<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6f61c7 elementor-widget elementor-widget-text-editor\" data-id=\"a6f61c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bas\u00e9s en Allemagne, nous op\u00e9rons \u00e0 l&rsquo;\u00e9chelle mondiale. Nous sommes pr\u00e9sents dans plus de 70 pays. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Entreprise Carri\u00e8re Pr\u00eat \u00e0 commencer ? Rejoindre notre \u00e9quipe Voir les postes \u00e0 pourvoir Espace de travail et culture Chez BioAnalyt, vous ferez partie d&rsquo;une \u00e9quipe agile et comp\u00e9tente qui<\/p>\n","protected":false},"author":1,"featured_media":19796,"parent":0,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-22523","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carri\u00e8re - Bioanalyt<\/title>\n<meta name=\"description\" content=\"Chez BioAnalyt, vous ferez partie d&#039;une \u00e9quipe agile et comp\u00e9tente qui collabore au-del\u00e0 des silos pour avoir un impact r\u00e9el.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bioanalyt.com\/career\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carri\u00e8re - Bioanalyt\" \/>\n<meta property=\"og:description\" content=\"Chez BioAnalyt, vous ferez partie d&#039;une \u00e9quipe agile et comp\u00e9tente qui collabore au-del\u00e0 des silos pour avoir un impact r\u00e9el.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bioanalyt.com\/career\/\" \/>\n<meta property=\"og:site_name\" content=\"Bioanalyt\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T07:53:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2025\/02\/career-slider-final.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1394\" \/>\n\t<meta property=\"og:image:height\" content=\"728\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/career\\\/\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/career\\\/\",\"name\":\"Carri\u00e8re - Bioanalyt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/career\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/career\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/career-slider-final.webp\",\"datePublished\":\"2024-10-16T09:34:18+00:00\",\"dateModified\":\"2025-12-18T07:53:19+00:00\",\"description\":\"Chez BioAnalyt, vous ferez partie d'une \u00e9quipe agile et comp\u00e9tente qui collabore au-del\u00e0 des silos pour avoir un impact r\u00e9el.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/career\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bioanalyt.com\\\/career\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/career\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/career-slider-final.webp\",\"contentUrl\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/career-slider-final.webp\",\"width\":1394,\"height\":728},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/career\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bioanalyt.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carri\u00e8re\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#website\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/\",\"name\":\"Bioanalyt\",\"description\":\"Measure for life\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bioanalyt.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#organization\",\"name\":\"Bioanalyt\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Logo-Horizontal.svg\",\"contentUrl\":\"https:\\\/\\\/www.bioanalyt.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Logo-Horizontal.svg\",\"width\":112,\"height\":64,\"caption\":\"Bioanalyt\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bioanalyt.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/bioanalyt\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BioAnalyt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carri\u00e8re - Bioanalyt","description":"Chez BioAnalyt, vous ferez partie d'une \u00e9quipe agile et comp\u00e9tente qui collabore au-del\u00e0 des silos pour avoir un impact r\u00e9el.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bioanalyt.com\/career\/","og_locale":"fr_FR","og_type":"article","og_title":"Carri\u00e8re - Bioanalyt","og_description":"Chez BioAnalyt, vous ferez partie d'une \u00e9quipe agile et comp\u00e9tente qui collabore au-del\u00e0 des silos pour avoir un impact r\u00e9el.","og_url":"https:\/\/www.bioanalyt.com\/career\/","og_site_name":"Bioanalyt","article_modified_time":"2025-12-18T07:53:19+00:00","og_image":[{"width":1394,"height":728,"url":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2025\/02\/career-slider-final.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bioanalyt.com\/career\/","url":"https:\/\/www.bioanalyt.com\/career\/","name":"Carri\u00e8re - Bioanalyt","isPartOf":{"@id":"https:\/\/www.bioanalyt.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bioanalyt.com\/career\/#primaryimage"},"image":{"@id":"https:\/\/www.bioanalyt.com\/career\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2025\/02\/career-slider-final.webp","datePublished":"2024-10-16T09:34:18+00:00","dateModified":"2025-12-18T07:53:19+00:00","description":"Chez BioAnalyt, vous ferez partie d'une \u00e9quipe agile et comp\u00e9tente qui collabore au-del\u00e0 des silos pour avoir un impact r\u00e9el.","breadcrumb":{"@id":"https:\/\/www.bioanalyt.com\/career\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bioanalyt.com\/career\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bioanalyt.com\/career\/#primaryimage","url":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2025\/02\/career-slider-final.webp","contentUrl":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2025\/02\/career-slider-final.webp","width":1394,"height":728},{"@type":"BreadcrumbList","@id":"https:\/\/www.bioanalyt.com\/career\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bioanalyt.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Carri\u00e8re"}]},{"@type":"WebSite","@id":"https:\/\/www.bioanalyt.com\/#website","url":"https:\/\/www.bioanalyt.com\/","name":"Bioanalyt","description":"Measure for life","publisher":{"@id":"https:\/\/www.bioanalyt.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bioanalyt.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.bioanalyt.com\/#organization","name":"Bioanalyt","url":"https:\/\/www.bioanalyt.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bioanalyt.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/09\/Logo-Horizontal.svg","contentUrl":"https:\/\/www.bioanalyt.com\/wp-content\/uploads\/2024\/09\/Logo-Horizontal.svg","width":112,"height":64,"caption":"Bioanalyt"},"image":{"@id":"https:\/\/www.bioanalyt.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/bioanalyt\/","https:\/\/www.youtube.com\/user\/BioAnalyt"]}]}},"_links":{"self":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/pages\/22523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/comments?post=22523"}],"version-history":[{"count":3,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/pages\/22523\/revisions"}],"predecessor-version":[{"id":23652,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/pages\/22523\/revisions\/23652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/media\/19796"}],"wp:attachment":[{"href":"https:\/\/www.bioanalyt.com\/fr\/wp-json\/wp\/v2\/media?parent=22523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}